{"id":2542,"date":"2023-09-21T13:09:08","date_gmt":"2023-09-21T11:09:08","guid":{"rendered":"http:\/\/2024.nord-bb.de\/?page_id=2542"},"modified":"2024-09-03T16:48:32","modified_gmt":"2024-09-03T14:48:32","slug":"wasserhaltung-ochsenwerder","status":"publish","type":"page","link":"https:\/\/nord-bb.de\/de\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-ochsenwerder\/","title":{"rendered":"Wasserhaltung Ochsenwerder"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2542\" class=\"elementor elementor-2542\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-927d4ac e-flex e-con-boxed e-con e-parent\" data-id=\"927d4ac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0aa849e e-con-full e-flex e-con e-child\" data-id=\"0aa849e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e54a4c elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"1e54a4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nord-bb.de\/leistungen\/we-drill\/projekt-wasserhaltung\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"990\" height=\"1771\" src=\"https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-AOchsenwerder-HH.jpg\" class=\"attachment-full size-full wp-image-2544\" alt=\"\" srcset=\"https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-AOchsenwerder-HH.jpg 990w, https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-AOchsenwerder-HH-168x300.jpg 168w, https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-AOchsenwerder-HH-572x1024.jpg 572w, https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-AOchsenwerder-HH-768x1374.jpg 768w, https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-AOchsenwerder-HH-859x1536.jpg 859w, https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-AOchsenwerder-HH-7x12.jpg 7w\" sizes=\"(max-width: 990px) 100vw, 990px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fd49369 e-con-full e-flex e-con e-child\" data-id=\"fd49369\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3d1005d e-con-full e-flex e-con e-child\" data-id=\"3d1005d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1415c44 e-con-full e-flex e-con e-child\" data-id=\"1415c44\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-10340a9 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"10340a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ochsenwerder Hamburg<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d619869 elementor-widget elementor-widget-text-editor\" data-id=\"d619869\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Bauherr:<\/strong>Lawaetz-Stiftung\u00a0<\/p><p><strong>Ort:<\/strong> Hamburg<\/p><p><strong>Gebirgsformation: <\/strong>Quat\u00e4r<\/p><p><strong>Bohrverfahren: <\/strong>Trockenbohrung<\/p><p>Anzahl Bohrungen: 5 Br. &#8211; 1 GWM<\/p><p>Bohrtiefe in m: 9,25<\/p><p>Bohrmeter gesamt: 46,25<\/p><p>Bohr-\u00d8 in mm: 419<\/p><p>Ausbaudaten:DN 200\/PVC<\/p><p>Zweck der Bohrung:<\/p><div class=\"page\" title=\"Page 1\"><div class=\"layoutArea\"><div class=\"column\"><p>Grundwasserabsenkung 5 Brunnen <br \/>1 Grundwassermessstelle<\/p><div class=\"page\" title=\"Page 1\"><div class=\"layoutArea\"><div class=\"column\"><p>Entspannungswasserhaltung mit einer Entnahmemenge von 200 m\u00b3\/h. 2 Wochen nach Beendigung der Wasserhaltung wurden die 5 Brunnen nach den Vorgaben der Wasserwirtschaft zur\u00fcckgebaut. Gestellung von Notstrom mit Fern\u00fcberwachung sowie kontinuierliche Datenaufzeichnung.<\/p><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a48dce elementor-widget elementor-widget-image\" data-id=\"3a48dce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nord-bb.de\/wp-content\/uploads\/2024\/09\/Lawaetz-Stiftung-Ochsenwerder-Br-1.jpg\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/nord-bb.de\/wp-content\/uploads\/elementor\/thumbs\/Lawaetz-Stiftung-Ochsenwerder-Br-1-qvjz6rfiswa3agw91xti7lajtnirrrurnwzxaqzy5o.jpg\" title=\"Lawaetz-Stiftung Ochsenwerder Br 1\" alt=\"Lawaetz-Stiftung Ochsenwerder Br 1\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ochsenwerder Hamburg Bauherr:Lawaetz-Stiftung\u00a0 Ort: Hamburg Gebirgsformation: Quat\u00e4r Bohrverfahren: Trockenbohrung Anzahl Bohrungen: 5 Br. &#8211; 1 GWM Bohrtiefe in m: 9,25 Bohrmeter gesamt: 46,25 Bohr-\u00d8 in mm: 419 Ausbaudaten:DN 200\/PVC Zweck der Bohrung: Grundwasserabsenkung 5 Brunnen 1 Grundwassermessstelle Entspannungswasserhaltung mit einer Entnahmemenge von 200 m\u00b3\/h. 2 Wochen nach Beendigung der Wasserhaltung wurden die 5 Brunnen nach [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":2527,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-2542","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wasserhaltung Ochsenwerder - NORD Bohr und Brunnenbau GmbH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nord-bb.de\/de\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-ochsenwerder\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wasserhaltung Ochsenwerder - NORD Bohr und Brunnenbau GmbH\" \/>\n<meta property=\"og:description\" content=\"Ochsenwerder Hamburg Bauherr:Lawaetz-Stiftung\u00a0 Ort: Hamburg Gebirgsformation: Quat\u00e4r Bohrverfahren: Trockenbohrung Anzahl Bohrungen: 5 Br. &#8211; 1 GWM Bohrtiefe in m: 9,25 Bohrmeter gesamt: 46,25 Bohr-\u00d8 in mm: 419 Ausbaudaten:DN 200\/PVC Zweck der Bohrung: Grundwasserabsenkung 5 Brunnen 1 Grundwassermessstelle Entspannungswasserhaltung mit einer Entnahmemenge von 200 m\u00b3\/h. 2 Wochen nach Beendigung der Wasserhaltung wurden die 5 Brunnen nach [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nord-bb.de\/de\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-ochsenwerder\/\" \/>\n<meta property=\"og:site_name\" content=\"NORD Bohr und Brunnenbau GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-03T14:48:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-AOchsenwerder-HH.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nord-bb.de\\\/leistungen\\\/we-drill\\\/projekt-wasserhaltung\\\/wasserhaltung-ochsenwerder\\\/\",\"url\":\"https:\\\/\\\/nord-bb.de\\\/leistungen\\\/we-drill\\\/projekt-wasserhaltung\\\/wasserhaltung-ochsenwerder\\\/\",\"name\":\"Wasserhaltung Ochsenwerder - NORD Bohr und Brunnenbau GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nord-bb.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nord-bb.de\\\/leistungen\\\/we-drill\\\/projekt-wasserhaltung\\\/wasserhaltung-ochsenwerder\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nord-bb.de\\\/leistungen\\\/we-drill\\\/projekt-wasserhaltung\\\/wasserhaltung-ochsenwerder\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nord-bb.de\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Wasser-AOchsenwerder-HH.jpg\",\"datePublished\":\"2023-09-21T11:09:08+00:00\",\"dateModified\":\"2024-09-03T14:48:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nord-bb.de\\\/leistungen\\\/we-drill\\\/projekt-wasserhaltung\\\/wasserhaltung-ochsenwerder\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nord-bb.de\\\/leistungen\\\/we-drill\\\/projekt-wasserhaltung\\\/wasserhaltung-ochsenwerder\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/nord-bb.de\\\/leistungen\\\/we-drill\\\/projekt-wasserhaltung\\\/wasserhaltung-ochsenwerder\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nord-bb.de\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Wasser-AOchsenwerder-HH.jpg\",\"contentUrl\":\"https:\\\/\\\/nord-bb.de\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Wasser-AOchsenwerder-HH.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nord-bb.de\\\/leistungen\\\/we-drill\\\/projekt-wasserhaltung\\\/wasserhaltung-ochsenwerder\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/nord-bb.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leistungen\",\"item\":\"https:\\\/\\\/nord-bb.de\\\/leistungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"WE DRILL.\",\"item\":\"https:\\\/\\\/nord-bb.de\\\/leistungen\\\/we-drill\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Projekt Wasserhaltung\",\"item\":\"https:\\\/\\\/nord-bb.de\\\/leistungen\\\/we-drill\\\/projekt-wasserhaltung\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Wasserhaltung Ochsenwerder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nord-bb.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/nord-bb.de\\\/de\\\/\",\"name\":\"NORD Bohr und Brunnenbau GmbH\",\"description\":\"Die Spezialisten f\u00fcr Bohr- und Brunnenbau-Technologien\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nord-bb.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wasserhaltung Ochsenwerder - NORD Bohr und Brunnenbau GmbH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nord-bb.de\/de\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-ochsenwerder\/","og_locale":"de_DE","og_type":"article","og_title":"Wasserhaltung Ochsenwerder - NORD Bohr und Brunnenbau GmbH","og_description":"Ochsenwerder Hamburg Bauherr:Lawaetz-Stiftung\u00a0 Ort: Hamburg Gebirgsformation: Quat\u00e4r Bohrverfahren: Trockenbohrung Anzahl Bohrungen: 5 Br. &#8211; 1 GWM Bohrtiefe in m: 9,25 Bohrmeter gesamt: 46,25 Bohr-\u00d8 in mm: 419 Ausbaudaten:DN 200\/PVC Zweck der Bohrung: Grundwasserabsenkung 5 Brunnen 1 Grundwassermessstelle Entspannungswasserhaltung mit einer Entnahmemenge von 200 m\u00b3\/h. 2 Wochen nach Beendigung der Wasserhaltung wurden die 5 Brunnen nach [&hellip;]","og_url":"https:\/\/nord-bb.de\/de\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-ochsenwerder\/","og_site_name":"NORD Bohr und Brunnenbau GmbH","article_modified_time":"2024-09-03T14:48:32+00:00","og_image":[{"url":"https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-AOchsenwerder-HH.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nord-bb.de\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-ochsenwerder\/","url":"https:\/\/nord-bb.de\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-ochsenwerder\/","name":"Wasserhaltung Ochsenwerder - NORD Bohr und Brunnenbau GmbH","isPartOf":{"@id":"https:\/\/nord-bb.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nord-bb.de\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-ochsenwerder\/#primaryimage"},"image":{"@id":"https:\/\/nord-bb.de\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-ochsenwerder\/#primaryimage"},"thumbnailUrl":"https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-AOchsenwerder-HH.jpg","datePublished":"2023-09-21T11:09:08+00:00","dateModified":"2024-09-03T14:48:32+00:00","breadcrumb":{"@id":"https:\/\/nord-bb.de\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-ochsenwerder\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nord-bb.de\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-ochsenwerder\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/nord-bb.de\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-ochsenwerder\/#primaryimage","url":"https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-AOchsenwerder-HH.jpg","contentUrl":"https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-AOchsenwerder-HH.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/nord-bb.de\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-ochsenwerder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/nord-bb.de\/"},{"@type":"ListItem","position":2,"name":"Leistungen","item":"https:\/\/nord-bb.de\/leistungen\/"},{"@type":"ListItem","position":3,"name":"WE DRILL.","item":"https:\/\/nord-bb.de\/leistungen\/we-drill\/"},{"@type":"ListItem","position":4,"name":"Projekt Wasserhaltung","item":"https:\/\/nord-bb.de\/leistungen\/we-drill\/projekt-wasserhaltung\/"},{"@type":"ListItem","position":5,"name":"Wasserhaltung Ochsenwerder"}]},{"@type":"WebSite","@id":"https:\/\/nord-bb.de\/de\/#website","url":"https:\/\/nord-bb.de\/de\/","name":"NORD Bohr und Brunnenbau GmbH","description":"Die Spezialisten f\u00fcr Bohr- und Brunnenbau-Technologien","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nord-bb.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/nord-bb.de\/de\/wp-json\/wp\/v2\/pages\/2542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nord-bb.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nord-bb.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nord-bb.de\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nord-bb.de\/de\/wp-json\/wp\/v2\/comments?post=2542"}],"version-history":[{"count":16,"href":"https:\/\/nord-bb.de\/de\/wp-json\/wp\/v2\/pages\/2542\/revisions"}],"predecessor-version":[{"id":3543,"href":"https:\/\/nord-bb.de\/de\/wp-json\/wp\/v2\/pages\/2542\/revisions\/3543"}],"up":[{"embeddable":true,"href":"https:\/\/nord-bb.de\/de\/wp-json\/wp\/v2\/pages\/2527"}],"wp:attachment":[{"href":"https:\/\/nord-bb.de\/de\/wp-json\/wp\/v2\/media?parent=2542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}