{"id":3756,"date":"2024-11-26T10:50:38","date_gmt":"2024-11-26T09:50:38","guid":{"rendered":"https:\/\/nord-bb.de\/?page_id=3756"},"modified":"2024-11-26T10:56:20","modified_gmt":"2024-11-26T09:56:20","slug":"karriere-portal","status":"publish","type":"page","link":"https:\/\/nord-bb.de\/de\/karriere-portal\/","title":{"rendered":"Karriereportal"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-3756","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Karriereportal - NORD Bohr und Brunnenbau GmbH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nord-bb.de\/de\/karriere-portal\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Karriereportal - NORD Bohr und Brunnenbau GmbH\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nord-bb.de\/de\/karriere-portal\/\" \/>\n<meta property=\"og:site_name\" content=\"NORD Bohr und Brunnenbau GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-26T09:56:20+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nord-bb.de\\\/karriere-portal\\\/\",\"url\":\"https:\\\/\\\/nord-bb.de\\\/karriere-portal\\\/\",\"name\":\"Karriereportal - NORD Bohr und Brunnenbau GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nord-bb.de\\\/de\\\/#website\"},\"datePublished\":\"2024-11-26T09:50:38+00:00\",\"dateModified\":\"2024-11-26T09:56:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nord-bb.de\\\/karriere-portal\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nord-bb.de\\\/karriere-portal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nord-bb.de\\\/karriere-portal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/nord-bb.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Karriereportal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nord-bb.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/nord-bb.de\\\/de\\\/\",\"name\":\"NORD Bohr und Brunnenbau GmbH\",\"description\":\"Die Spezialisten f\u00fcr Bohr- und Brunnenbau-Technologien\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nord-bb.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Karriereportal - NORD Bohr und Brunnenbau GmbH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nord-bb.de\/de\/karriere-portal\/","og_locale":"de_DE","og_type":"article","og_title":"Karriereportal - NORD Bohr und Brunnenbau GmbH","og_url":"https:\/\/nord-bb.de\/de\/karriere-portal\/","og_site_name":"NORD Bohr und Brunnenbau GmbH","article_modified_time":"2024-11-26T09:56:20+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nord-bb.de\/karriere-portal\/","url":"https:\/\/nord-bb.de\/karriere-portal\/","name":"Karriereportal - NORD Bohr und Brunnenbau GmbH","isPartOf":{"@id":"https:\/\/nord-bb.de\/de\/#website"},"datePublished":"2024-11-26T09:50:38+00:00","dateModified":"2024-11-26T09:56:20+00:00","breadcrumb":{"@id":"https:\/\/nord-bb.de\/karriere-portal\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nord-bb.de\/karriere-portal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nord-bb.de\/karriere-portal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/nord-bb.de\/"},{"@type":"ListItem","position":2,"name":"Karriereportal"}]},{"@type":"WebSite","@id":"https:\/\/nord-bb.de\/de\/#website","url":"https:\/\/nord-bb.de\/de\/","name":"NORD Bohr und Brunnenbau GmbH","description":"Die Spezialisten f\u00fcr Bohr- und Brunnenbau-Technologien","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nord-bb.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/nord-bb.de\/de\/wp-json\/wp\/v2\/pages\/3756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nord-bb.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nord-bb.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nord-bb.de\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nord-bb.de\/de\/wp-json\/wp\/v2\/comments?post=3756"}],"version-history":[{"count":4,"href":"https:\/\/nord-bb.de\/de\/wp-json\/wp\/v2\/pages\/3756\/revisions"}],"predecessor-version":[{"id":3762,"href":"https:\/\/nord-bb.de\/de\/wp-json\/wp\/v2\/pages\/3756\/revisions\/3762"}],"wp:attachment":[{"href":"https:\/\/nord-bb.de\/de\/wp-json\/wp\/v2\/media?parent=3756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}