{"id":2534,"date":"2023-09-21T13:02:44","date_gmt":"2023-09-21T11:02:44","guid":{"rendered":"http:\/\/2024.nord-bb.de\/?page_id=2534"},"modified":"2024-10-02T13:44:14","modified_gmt":"2024-10-02T11:44:14","slug":"wasserhaltung-alter-wall","status":"publish","type":"page","link":"https:\/\/nord-bb.de\/en\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-alter-wall\/","title":{"rendered":"Wasserhaltung Alter Wall"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"2534\" class=\"elementor elementor-2534\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a43ef98 e-flex e-con-boxed e-con e-parent\" data-id=\"a43ef98\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9a956ba e-con-full e-flex e-con e-child\" data-id=\"9a956ba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9371999 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"9371999\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nord-bb.de\/en\/leistungen\/we-drill\/projekt-wasserhaltung\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"990\" height=\"1771\" src=\"https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-Alter-Wall-HH.jpg\" class=\"attachment-full size-full wp-image-2536\" alt=\"\" srcset=\"https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-Alter-Wall-HH.jpg 990w, https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-Alter-Wall-HH-168x300.jpg 168w, https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-Alter-Wall-HH-572x1024.jpg 572w, https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-Alter-Wall-HH-768x1374.jpg 768w, https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-Alter-Wall-HH-859x1536.jpg 859w, https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-Alter-Wall-HH-7x12.jpg 7w\" sizes=\"(max-width: 990px) 100vw, 990px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca73be8 e-con-full e-flex e-con e-child\" data-id=\"ca73be8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6d0b097 e-con-full e-flex e-con e-child\" data-id=\"6d0b097\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ddb4f60 e-con-full e-flex e-con e-child\" data-id=\"ddb4f60\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3096ef7 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"3096ef7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Alter Wall Hamburg<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-feaba7b elementor-widget elementor-widget-text-editor\" data-id=\"feaba7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Builder: <\/strong>Lawaetz-Stiftung<\/p><p><strong>Location:<\/strong> Hamburg<\/p><p><strong>Mountain formation: <\/strong>Quaternary<\/p><p><strong>Drilling method: <\/strong>Dewatering<\/p><p>Number of holes: 17<\/p><p>Drilling depth in m: 35<\/p><p>Total drilling meters: 595<\/p><p>Drilling \u00d8 in mm: 300<\/p><p>Expansion data: DN 150 \/ DN 115<\/p><p>Purpose of the drilling:<\/p><div class=\"page\" title=\"Page 1\"><div class=\"layoutArea\"><div class=\"column\"><p>Lowering well, internal level, iron removal system.<\/p><div class=\"page\" title=\"Page 1\"><div class=\"layoutArea\"><div class=\"column\"><p>Dewatering or lowering within a trough excavation pit. All wells were equipped with conveyor systems. The extracted groundwater was drained into the Alsterfleet via a sand trap with a neutralization and de-icing system. The water levels within the excavation pit were monitored using 7 internal gauges. The entire system was maintained and operated over 667 calendar days. After the dewatering was completed, all bridges and GWM were dismantled in accordance with official specifications.<\/p><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e23a81e elementor-widget elementor-widget-image\" data-id=\"e23a81e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/nord-bb.de\/wp-content\/uploads\/2024\/09\/Alter-Wall-GWM-2C-komplett.jpg\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/nord-bb.de\/wp-content\/uploads\/elementor\/thumbs\/Alter-Wall-GWM-2C-komplett-qvjz6rfk54wx1rpxddodrn6q49kbhr1gf7ydls5yao.jpg\" title=\"Alter Wall GWM 2C komplett\" alt=\"Alter Wall GWM 2C komplett\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Alter Wall Hamburg Bauherr: Lawaetz-Stiftung Ort: Hamburg Gebirgsformation: Quart\u00e4r Bohrverfahren: Wasserhaltung Anzahl Bohrungen: 17 Bohrtiefe in m: 35 Bohrmeter gesamt: 595 Bohr-\u00d8 in mm: 300 Ausbaudaten:DN 150 \/ DN 115 Zweck der Bohrung: Absenkbrunnen, Innenpegel, Enteisenungsanlage. Wasserhaltung bzw. Absenkung innerhalb einer Trog Baugrube. Alle Brunnen wurden mit F\u00f6rderanlagen ausger\u00fcstet. Das gef\u00f6rderte Grundwasser wurde \u00fcber einen [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":2527,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-2534","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wasserhaltung Alter Wall - NORD Bohr und Brunnenbau GmbH<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nord-bb.de\/en\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-alter-wall\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wasserhaltung Alter Wall - NORD Bohr und Brunnenbau GmbH\" \/>\n<meta property=\"og:description\" content=\"Alter Wall Hamburg Bauherr: Lawaetz-Stiftung Ort: Hamburg Gebirgsformation: Quart\u00e4r Bohrverfahren: Wasserhaltung Anzahl Bohrungen: 17 Bohrtiefe in m: 35 Bohrmeter gesamt: 595 Bohr-\u00d8 in mm: 300 Ausbaudaten:DN 150 \/ DN 115 Zweck der Bohrung: Absenkbrunnen, Innenpegel, Enteisenungsanlage. Wasserhaltung bzw. Absenkung innerhalb einer Trog Baugrube. Alle Brunnen wurden mit F\u00f6rderanlagen ausger\u00fcstet. Das gef\u00f6rderte Grundwasser wurde \u00fcber einen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nord-bb.de\/en\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-alter-wall\/\" \/>\n<meta property=\"og:site_name\" content=\"NORD Bohr und Brunnenbau GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-02T11:44:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-Alter-Wall-HH.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nord-bb.de\\\/leistungen\\\/we-drill\\\/projekt-wasserhaltung\\\/wasserhaltung-alter-wall\\\/\",\"url\":\"https:\\\/\\\/nord-bb.de\\\/leistungen\\\/we-drill\\\/projekt-wasserhaltung\\\/wasserhaltung-alter-wall\\\/\",\"name\":\"Wasserhaltung Alter Wall - NORD Bohr und Brunnenbau GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nord-bb.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/nord-bb.de\\\/leistungen\\\/we-drill\\\/projekt-wasserhaltung\\\/wasserhaltung-alter-wall\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/nord-bb.de\\\/leistungen\\\/we-drill\\\/projekt-wasserhaltung\\\/wasserhaltung-alter-wall\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/nord-bb.de\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Wasser-Alter-Wall-HH.jpg\",\"datePublished\":\"2023-09-21T11:02:44+00:00\",\"dateModified\":\"2024-10-02T11:44:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nord-bb.de\\\/leistungen\\\/we-drill\\\/projekt-wasserhaltung\\\/wasserhaltung-alter-wall\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nord-bb.de\\\/leistungen\\\/we-drill\\\/projekt-wasserhaltung\\\/wasserhaltung-alter-wall\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/nord-bb.de\\\/leistungen\\\/we-drill\\\/projekt-wasserhaltung\\\/wasserhaltung-alter-wall\\\/#primaryimage\",\"url\":\"https:\\\/\\\/nord-bb.de\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Wasser-Alter-Wall-HH.jpg\",\"contentUrl\":\"https:\\\/\\\/nord-bb.de\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Wasser-Alter-Wall-HH.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nord-bb.de\\\/leistungen\\\/we-drill\\\/projekt-wasserhaltung\\\/wasserhaltung-alter-wall\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/nord-bb.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leistungen\",\"item\":\"https:\\\/\\\/nord-bb.de\\\/leistungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"WE DRILL.\",\"item\":\"https:\\\/\\\/nord-bb.de\\\/leistungen\\\/we-drill\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Projekt Wasserhaltung\",\"item\":\"https:\\\/\\\/nord-bb.de\\\/leistungen\\\/we-drill\\\/projekt-wasserhaltung\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Wasserhaltung Alter Wall\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nord-bb.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/nord-bb.de\\\/de\\\/\",\"name\":\"NORD Bohr und Brunnenbau GmbH\",\"description\":\"Die Spezialisten f\u00fcr Bohr- und Brunnenbau-Technologien\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nord-bb.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wasserhaltung Alter Wall - NORD Bohr und Brunnenbau GmbH","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nord-bb.de\/en\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-alter-wall\/","og_locale":"en_GB","og_type":"article","og_title":"Wasserhaltung Alter Wall - NORD Bohr und Brunnenbau GmbH","og_description":"Alter Wall Hamburg Bauherr: Lawaetz-Stiftung Ort: Hamburg Gebirgsformation: Quart\u00e4r Bohrverfahren: Wasserhaltung Anzahl Bohrungen: 17 Bohrtiefe in m: 35 Bohrmeter gesamt: 595 Bohr-\u00d8 in mm: 300 Ausbaudaten:DN 150 \/ DN 115 Zweck der Bohrung: Absenkbrunnen, Innenpegel, Enteisenungsanlage. Wasserhaltung bzw. Absenkung innerhalb einer Trog Baugrube. Alle Brunnen wurden mit F\u00f6rderanlagen ausger\u00fcstet. Das gef\u00f6rderte Grundwasser wurde \u00fcber einen [&hellip;]","og_url":"https:\/\/nord-bb.de\/en\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-alter-wall\/","og_site_name":"NORD Bohr und Brunnenbau GmbH","article_modified_time":"2024-10-02T11:44:14+00:00","og_image":[{"url":"https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-Alter-Wall-HH.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nord-bb.de\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-alter-wall\/","url":"https:\/\/nord-bb.de\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-alter-wall\/","name":"Wasserhaltung Alter Wall - NORD Bohr und Brunnenbau GmbH","isPartOf":{"@id":"https:\/\/nord-bb.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/nord-bb.de\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-alter-wall\/#primaryimage"},"image":{"@id":"https:\/\/nord-bb.de\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-alter-wall\/#primaryimage"},"thumbnailUrl":"https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-Alter-Wall-HH.jpg","datePublished":"2023-09-21T11:02:44+00:00","dateModified":"2024-10-02T11:44:14+00:00","breadcrumb":{"@id":"https:\/\/nord-bb.de\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-alter-wall\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nord-bb.de\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-alter-wall\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/nord-bb.de\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-alter-wall\/#primaryimage","url":"https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-Alter-Wall-HH.jpg","contentUrl":"https:\/\/nord-bb.de\/wp-content\/uploads\/2023\/09\/Wasser-Alter-Wall-HH.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/nord-bb.de\/leistungen\/we-drill\/projekt-wasserhaltung\/wasserhaltung-alter-wall\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/nord-bb.de\/"},{"@type":"ListItem","position":2,"name":"Leistungen","item":"https:\/\/nord-bb.de\/leistungen\/"},{"@type":"ListItem","position":3,"name":"WE DRILL.","item":"https:\/\/nord-bb.de\/leistungen\/we-drill\/"},{"@type":"ListItem","position":4,"name":"Projekt Wasserhaltung","item":"https:\/\/nord-bb.de\/leistungen\/we-drill\/projekt-wasserhaltung\/"},{"@type":"ListItem","position":5,"name":"Wasserhaltung Alter Wall"}]},{"@type":"WebSite","@id":"https:\/\/nord-bb.de\/de\/#website","url":"https:\/\/nord-bb.de\/de\/","name":"NORD Bohr und Brunnenbau GmbH","description":"Die Spezialisten f\u00fcr Bohr- und Brunnenbau-Technologien","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nord-bb.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/nord-bb.de\/en\/wp-json\/wp\/v2\/pages\/2534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nord-bb.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nord-bb.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nord-bb.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/nord-bb.de\/en\/wp-json\/wp\/v2\/comments?post=2534"}],"version-history":[{"count":25,"href":"https:\/\/nord-bb.de\/en\/wp-json\/wp\/v2\/pages\/2534\/revisions"}],"predecessor-version":[{"id":3688,"href":"https:\/\/nord-bb.de\/en\/wp-json\/wp\/v2\/pages\/2534\/revisions\/3688"}],"up":[{"embeddable":true,"href":"https:\/\/nord-bb.de\/en\/wp-json\/wp\/v2\/pages\/2527"}],"wp:attachment":[{"href":"https:\/\/nord-bb.de\/en\/wp-json\/wp\/v2\/media?parent=2534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}